{"id":8948,"date":"2011-08-10T17:12:12","date_gmt":"2011-08-10T15:12:12","guid":{"rendered":"\/parlonsen\/?p=8948"},"modified":"2013-03-14T13:32:20","modified_gmt":"2013-03-14T11:32:20","slug":"ballade-en-perigord-avec-les-aines-de-montgaillard","status":"publish","type":"post","link":"https:\/\/www.o-p-i.fr\/parlonsen\/parlons-en\/culture\/ballade-en-perigord-avec-les-aines-de-montgaillard\/","title":{"rendered":"Ballade en P\u00e9rigord avec \u00ab\u00a0les A\u00een\u00e9s de Montgaillard\u00a0\u00bb&#8230;"},"content":{"rendered":"<p>Apr\u00e8s l&rsquo;Aveyron l&rsquo;an pass\u00e9, c&rsquo;est \u00e0 une belle sortie en P\u00e9rigord que vous invitent les \u00ab\u00a0A\u00een\u00e9s de Montgaillard\u00a0\u00bb le 6 septembre 2011.<!--more--><\/p>\n<figure id=\"attachment_8971\" aria-describedby=\"caption-attachment-8971\" style=\"width: 379px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/caleches.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8971\" title=\"caleches\" src=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/caleches.jpg?resize=379%2C163&#038;ssl=1\" alt=\"Balade en cal\u00e8che\" width=\"379\" height=\"163\" srcset=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/caleches.jpg?w=379&amp;ssl=1 379w, https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/caleches.jpg?resize=300%2C129&amp;ssl=1 300w\" sizes=\"auto, (max-width: 379px) 100vw, 379px\" \/><\/a><figcaption id=\"caption-attachment-8971\" class=\"wp-caption-text\">Balade en cal\u00e8che<\/figcaption><\/figure>\n<p><strong>Programme de la journ\u00e9e:<\/strong><\/p>\n<p>7h30 D\u00e9part de <strong>MONTGAILLARD<\/strong><\/p>\n<p>10h30 Arriv\u00e9e \u00e0 <strong>MAZEYROLLES<\/strong>, visite des installations du site et d\u00e9part pour une promenade en cal\u00e8che. La balade sera agr\u00e9ment\u00e9e par \u00ab\u00a0un arr\u00eat ap\u00e9ritif\u00a0\u00bb et une \u00ab\u00a0pose photo\u00a0\u00bb.<\/p>\n<p>12h30 Repas gastronomique au restaurant du village. au menu :<\/p>\n<p>Ap\u00e9ritif aux noix<br \/>\nSoupe Paysanne<br \/>\nSalade P\u00e9rigourdine avec rillettes de canard<br \/>\nConfit de canard avec ses pommes de terre sarladaises<br \/>\nPlateau de Fromages<br \/>\nG\u00e2teau aux Noix cr\u00e8me patissi\u00e8re<br \/>\nCaf\u00e9<br \/>\nVin du Pays<br \/>\nPain de campagne au levain<\/p>\n<figure id=\"attachment_8972\" aria-describedby=\"caption-attachment-8972\" style=\"width: 386px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/montpazier.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8972\" title=\"montpazier\" src=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/montpazier.jpg?resize=386%2C221&#038;ssl=1\" alt=\"Monpazier\" width=\"386\" height=\"221\" srcset=\"https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/montpazier.jpg?w=386&amp;ssl=1 386w, https:\/\/i0.wp.com\/www.o-p-i.fr\/parlonsen\/wp-content\/uploads\/montpazier.jpg?resize=300%2C171&amp;ssl=1 300w\" sizes=\"auto, (max-width: 386px) 100vw, 386px\" \/><\/a><figcaption id=\"caption-attachment-8972\" class=\"wp-caption-text\">Monpazier<\/figcaption><\/figure>\n<p>15h30 D\u00e9couverte de l&rsquo;un des joyaux de l&rsquo;architecture m\u00e9di\u00e9vale du P\u00e9rigord, <strong>\u00ab\u00a0La bastide de Monpazier\u00a0\u00bb<\/strong>. Construite en 1284, elle est class\u00e9e par les Monuments Historiques.<\/p>\n<p>17h Retour vers Montgaillard<\/p>\n<p><strong>Tarif,<\/strong> compris voyage,d\u00e9jeuner au restaurant et prestations mentionn\u00e9es dans le programme:<\/p>\n<p>70 \u20acuros par personne<br \/>\n65 \u20acuros pour les membres du club des A\u00een\u00e9s.<\/p>\n<p>Inscription avant le 25 par t\u00e9l\u00e9phone au 05 63 40 56 67<\/p>\n<p><em>Communiqu\u00e9 du Club des \u00ab\u00a0A\u00een\u00e9s de Montgaillard\u00a0\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\">Apr\u00e8s l&rsquo;Aveyron l&rsquo;an pass\u00e9, c&rsquo;est \u00e0 une belle sortie en P\u00e9rigord que vous invitent les \u00ab\u00a0A\u00een\u00e9s de Montgaillard\u00a0\u00bb le 6 septembre 2011.<\/div>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[828,1,54,31,1019],"tags":[82,659,1030,1031,1035],"class_list":{"0":"post-8948","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-au-pays-des-tescous","7":"category-culture","8":"category-loisirs","9":"category-montgaillard","10":"category-n-64-aout-2011","11":"tag-aines","12":"tag-voyage","13":"tag-mazeyrolles","14":"tag-monpazier","15":"tag-balade"},"jetpack_featured_media_url":"","views":{"total":0,"cached_at":"","cached_date":1738516150},"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pg7Wxj-2kk","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/posts\/8948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/comments?post=8948"}],"version-history":[{"count":0,"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/posts\/8948\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/media?parent=8948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/categories?post=8948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.o-p-i.fr\/parlonsen\/wp-json\/wp\/v2\/tags?post=8948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}